{"id":2191,"date":"2025-11-24T05:25:42","date_gmt":"2025-11-24T05:25:42","guid":{"rendered":"https:\/\/paperjewelz.com\/?page_id=2191"},"modified":"2025-11-24T05:25:46","modified_gmt":"2025-11-24T05:25:46","slug":"new-collection","status":"publish","type":"page","link":"https:\/\/paperjewelz.com\/index.php\/new-collection\/","title":{"rendered":"New Collection"},"content":{"rendered":"\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2192\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2714\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298446&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2714\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-scaled.jpg?fit=525%2C394&amp;ssl=1\" data-attachment-id=\"2192\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2714\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298446&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2714\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-scaled.jpg?fit=525%2C394&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 1 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"2192\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2192\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2193\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2718\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298591&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2718\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-scaled.jpg?fit=525%2C394&amp;ssl=1\" data-attachment-id=\"2193\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2718\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298591&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2718\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-scaled.jpg?fit=525%2C394&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 2 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-1024x768.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-1024x768.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-1024x768.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-1024x768.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-1024x768.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-1024x768.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"2193\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2193\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-1024x768.jpg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2718-1024x768.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2194\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2722\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298668&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2722\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-scaled.jpg?fit=525%2C394&amp;ssl=1\" data-attachment-id=\"2194\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2722\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298668&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2722\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-scaled.jpg?fit=525%2C394&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 3 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-1024x768.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-1024x768.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-1024x768.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-1024x768.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-1024x768.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-1024x768.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"2194\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2194\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-1024x768.jpg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2722-1024x768.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2195\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2725\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298705&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2725\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-scaled.jpg?fit=525%2C394&amp;ssl=1\" data-attachment-id=\"2195\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2725\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298705&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2725\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-scaled.jpg?fit=525%2C394&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 4 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-1024x768.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-1024x768.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-1024x768.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-1024x768.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-1024x768.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-1024x768.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"2195\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2195\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-1024x768.jpg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2725-1024x768.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2196\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2726\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298818&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2726\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-scaled.jpg?fit=525%2C394&amp;ssl=1\" data-attachment-id=\"2196\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2726\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763298818&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2726\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-scaled.jpg?fit=525%2C394&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 5 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-1024x768.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-1024x768.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-1024x768.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-1024x768.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-1024x768.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-1024x768.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"2196\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2196\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-1024x768.jpg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2726-1024x768.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2197\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2729\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763299296&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2729\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-scaled.jpg?fit=525%2C394&amp;ssl=1\" data-attachment-id=\"2197\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2729\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763299296&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2729\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-scaled.jpg?fit=525%2C394&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 6 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-1024x768.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-1024x768.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-1024x768.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-1024x768.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-1024x768.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-1024x768.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"2197\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2197\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-1024x768.jpg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2729-1024x768.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2198\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2730\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763299515&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2730\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-scaled.jpg?fit=525%2C394&amp;ssl=1\" data-attachment-id=\"2198\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2730\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-scaled.jpg?fit=2560%2C1920&amp;ssl=1\" data-orig-size=\"2560,1920\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763299515&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2730\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-scaled.jpg?fit=525%2C394&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 7 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-1024x768.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-1024x768.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-1024x768.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-1024x768.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-1024x768.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-1024x768.jpg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"2198\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2198\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-1024x768.jpg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2730-1024x768.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2199\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2734\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300389&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2734\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2199\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2734\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300389&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2734\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 8 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2199\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2199\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2734-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2200\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2746\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300515&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2746\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2200\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2746\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300515&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2746\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 9 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2200\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2200\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2746-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2201\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2762\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300651&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2762\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2201\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2762\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300651&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2762\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 10 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2201\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2201\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2762-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2202\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2766\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300684&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2766\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2202\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2766\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300684&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2766\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 11 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2202\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2202\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2766-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2203\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2769\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300718&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2769\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2203\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2769\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300718&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2769\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 12 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2203\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2203\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2769-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2204\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2773\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300771&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2773\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2204\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2773\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300771&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2773\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 13 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2204\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2204\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2773-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2205\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2778\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300825&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2778\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2205\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2778\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763300825&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2778\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 14 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2205\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2205\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2778-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2206\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2792\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301036&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2792\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2206\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2792\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301036&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2792\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 15 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2206\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2206\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2792-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2207\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2793\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301071&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2793\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2207\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2793\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301071&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2793\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 16 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2207\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2207\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2793-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2208\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2797\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301112&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2797\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2208\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2797\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301112&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2797\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 17 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2208\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2208\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2797-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2209\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2801\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301154&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2801\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2209\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2801\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301154&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2801\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 18 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2209\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2209\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2801-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2210\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2809\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301225&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2809\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2210\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2809\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301225&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2809\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 19 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2210\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2210\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2809-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2211\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2812\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301286&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2812\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2211\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2812\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301286&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2812\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 20 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2211\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2211\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2812-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2212\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2816\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301352&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2816\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2212\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2816\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301352&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2816\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 21 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2212\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2212\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2816-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2213\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2817\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301420&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2817\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2213\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2817\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301420&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2817\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 22 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2213\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2213\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2817-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2214\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2824\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301433&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2824\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2214\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2824\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301433&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2824\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 23 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2214\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2214\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2824-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2215\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2849\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301703&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2849\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2215\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2849\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301703&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2849\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 24 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2215\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2215\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2849-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2216\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2861\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301758&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2861\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2216\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2861\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301758&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2861\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 25 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2216\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2216\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2861-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2217\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2869\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301813&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2869\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2217\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2869\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301813&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2869\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 26 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2217\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2217\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2869-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2218\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2874\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301864&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2874\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2218\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2874\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301864&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2874\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 27 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2218\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2218\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2874-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2219\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2884\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301925&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2884\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2219\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2884\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301925&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2884\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 28 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2219\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2219\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2884-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2220\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2892\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301978&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2892\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2220\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2892\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763301978&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2892\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 29 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2220\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2220\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2892-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2221\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2897\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302026&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2897\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2221\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2897\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302026&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2897\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 30 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2221\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2221\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2897-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2222\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2908\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302122&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2908\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2222\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2908\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302122&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2908\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 31 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2222\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2222\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2908-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2223\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2916\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302214&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2916\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2223\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2916\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302214&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.058823529411765&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2916\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 32 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2223\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2223\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2916-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2224\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2925\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302306&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2925\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2224\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2925\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302306&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2925\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 33 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2224\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2224\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2925-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2225\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2926\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302348&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2926\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2225\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2926\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302348&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;200&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2926\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 34 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2225\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2225\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2926-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2226\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2929\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302390&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2929\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2226\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2929\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302390&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2929\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 35 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2226\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2226\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2929-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2227\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2940\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302468&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2940\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2227\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2940\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302468&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2940\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 36 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2227\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2227\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2940-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2228\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2941\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302592&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2941\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2228\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2941\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302592&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2941\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 37 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2228\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2228\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2941-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2229\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2944\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302667&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2944\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2229\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2944\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302667&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2944\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 38 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2229\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2229\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2944-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2230\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2952\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302816&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2952\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2230\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2952\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302816&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2952\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 39 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2230\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2230\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2952-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2231\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2960\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302883&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2960\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2231\" data-permalink=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/img_2960\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1763302883&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;125&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_2960\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-scaled.jpg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 40 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-768x1024.jpg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-768x1024.jpg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-768x1024.jpg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-768x1024.jpg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-768x1024.jpg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-768x1024.jpg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2231\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2231\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-768x1024.jpg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2960-768x1024.jpg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2116\" data-permalink=\"https:\/\/paperjewelz.com\/a2f86a9c-fb3d-4a96-866d-10bba8568043\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608288&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"A2F86A9C-FB3D-4A96-866D-10BBA8568043\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2116\" data-permalink=\"https:\/\/paperjewelz.com\/a2f86a9c-fb3d-4a96-866d-10bba8568043\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608288&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"A2F86A9C-FB3D-4A96-866D-10BBA8568043\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 41 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2116\" data-link=\"https:\/\/paperjewelz.com\/a2f86a9c-fb3d-4a96-866d-10bba8568043\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A2F86A9C-FB3D-4A96-866D-10BBA8568043-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2119\" data-permalink=\"https:\/\/paperjewelz.com\/e86ef3f6-06d0-4fbc-8f94-ca86cc593261\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608325&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.008695652173913&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"E86EF3F6-06D0-4FBC-8F94-CA86CC593261\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2119\" data-permalink=\"https:\/\/paperjewelz.com\/e86ef3f6-06d0-4fbc-8f94-ca86cc593261\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608325&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.008695652173913&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"E86EF3F6-06D0-4FBC-8F94-CA86CC593261\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 42 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2119\" data-link=\"https:\/\/paperjewelz.com\/e86ef3f6-06d0-4fbc-8f94-ca86cc593261\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/E86EF3F6-06D0-4FBC-8F94-CA86CC593261-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2107\" data-permalink=\"https:\/\/paperjewelz.com\/006642a7-a24a-49b8-93a8-d9ab98634ffe\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605955&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"006642A7-A24A-49B8-93A8-D9AB98634FFE\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2107\" data-permalink=\"https:\/\/paperjewelz.com\/006642a7-a24a-49b8-93a8-d9ab98634ffe\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605955&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"006642A7-A24A-49B8-93A8-D9AB98634FFE\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 43 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2107\" data-link=\"https:\/\/paperjewelz.com\/006642a7-a24a-49b8-93a8-d9ab98634ffe\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/006642A7-A24A-49B8-93A8-D9AB98634FFE-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2096\" data-permalink=\"https:\/\/paperjewelz.com\/9f30c920-c94a-410b-afbf-10bf79f10f7b\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605722&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0097087378640777&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"9F30C920-C94A-410B-AFBF-10BF79F10F7B\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2096\" data-permalink=\"https:\/\/paperjewelz.com\/9f30c920-c94a-410b-afbf-10bf79f10f7b\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605722&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0097087378640777&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"9F30C920-C94A-410B-AFBF-10BF79F10F7B\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 44 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2096\" data-link=\"https:\/\/paperjewelz.com\/9f30c920-c94a-410b-afbf-10bf79f10f7b\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9F30C920-C94A-410B-AFBF-10BF79F10F7B-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2097\" data-permalink=\"https:\/\/paperjewelz.com\/8960e0f9-b63d-4cff-a0f8-2eca88251048\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605760&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0095238095238095&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"8960E0F9-B63D-4CFF-A0F8-2ECA88251048\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2097\" data-permalink=\"https:\/\/paperjewelz.com\/8960e0f9-b63d-4cff-a0f8-2eca88251048\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605760&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0095238095238095&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"8960E0F9-B63D-4CFF-A0F8-2ECA88251048\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 45 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2097\" data-link=\"https:\/\/paperjewelz.com\/8960e0f9-b63d-4cff-a0f8-2eca88251048\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8960E0F9-B63D-4CFF-A0F8-2ECA88251048-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2099\" data-permalink=\"https:\/\/paperjewelz.com\/82574435-7c66-4776-9e5f-6dda18edef71\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71.jpeg?fit=2292%2C2539&amp;ssl=1\" data-orig-size=\"2292,2539\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605678&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0091743119266055&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"82574435-7C66-4776-9E5F-6DDA18EDEF71\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71.jpeg?fit=525%2C582&amp;ssl=1\" data-attachment-id=\"2099\" data-permalink=\"https:\/\/paperjewelz.com\/82574435-7c66-4776-9e5f-6dda18edef71\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71.jpeg?fit=2292%2C2539&amp;ssl=1\" data-orig-size=\"2292,2539\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605678&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0091743119266055&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"82574435-7C66-4776-9E5F-6DDA18EDEF71\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71.jpeg?fit=525%2C582&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 46 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71-924x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71-924x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71-924x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71-924x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71-924x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71-924x1024.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"2539\" data-id=\"2099\" data-link=\"https:\/\/paperjewelz.com\/82574435-7c66-4776-9e5f-6dda18edef71\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71-924x1024.jpeg\" data-width=\"2292\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/82574435-7C66-4776-9E5F-6DDA18EDEF71-924x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2100\" data-permalink=\"https:\/\/paperjewelz.com\/cf4c8b67-8c8f-4d4a-abb1-dda798f52e63\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605620&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2100\" data-permalink=\"https:\/\/paperjewelz.com\/cf4c8b67-8c8f-4d4a-abb1-dda798f52e63\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605620&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 47 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2100\" data-link=\"https:\/\/paperjewelz.com\/cf4c8b67-8c8f-4d4a-abb1-dda798f52e63\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/CF4C8B67-8C8F-4D4A-ABB1-DDA798F52E63-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2101\" data-permalink=\"https:\/\/paperjewelz.com\/6b4789b6-b345-4288-bd8a-9ff3f9bce443\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608242&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6B4789B6-B345-4288-BD8A-9FF3F9BCE443\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2101\" data-permalink=\"https:\/\/paperjewelz.com\/6b4789b6-b345-4288-bd8a-9ff3f9bce443\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608242&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6B4789B6-B345-4288-BD8A-9FF3F9BCE443\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 48 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2101\" data-link=\"https:\/\/paperjewelz.com\/6b4789b6-b345-4288-bd8a-9ff3f9bce443\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6B4789B6-B345-4288-BD8A-9FF3F9BCE443-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2095\" data-permalink=\"https:\/\/paperjewelz.com\/3e3d93fe-6979-4224-8d32-30ea36872c69\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605833&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0093457943925234&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"3E3D93FE-6979-4224-8D32-30EA36872C69\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2095\" data-permalink=\"https:\/\/paperjewelz.com\/3e3d93fe-6979-4224-8d32-30ea36872c69\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605833&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0093457943925234&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"3E3D93FE-6979-4224-8D32-30EA36872C69\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 49 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2095\" data-link=\"https:\/\/paperjewelz.com\/3e3d93fe-6979-4224-8d32-30ea36872c69\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3E3D93FE-6979-4224-8D32-30EA36872C69-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2094\" data-permalink=\"https:\/\/paperjewelz.com\/6dd582e8-79f1-49c9-aa16-52d3f2842c7d\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605869&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6DD582E8-79F1-49C9-AA16-52D3F2842C7D\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2094\" data-permalink=\"https:\/\/paperjewelz.com\/6dd582e8-79f1-49c9-aa16-52d3f2842c7d\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605869&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6DD582E8-79F1-49C9-AA16-52D3F2842C7D\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 50 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2094\" data-link=\"https:\/\/paperjewelz.com\/6dd582e8-79f1-49c9-aa16-52d3f2842c7d\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6DD582E8-79F1-49C9-AA16-52D3F2842C7D-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2093\" data-permalink=\"https:\/\/paperjewelz.com\/7177eb9b-1524-4a5c-8e55-a70f0ef198eb\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605897&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7177EB9B-1524-4A5C-8E55-A70F0EF198EB\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2093\" data-permalink=\"https:\/\/paperjewelz.com\/7177eb9b-1524-4a5c-8e55-a70f0ef198eb\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605897&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7177EB9B-1524-4A5C-8E55-A70F0EF198EB\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 51 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2093\" data-link=\"https:\/\/paperjewelz.com\/7177eb9b-1524-4a5c-8e55-a70f0ef198eb\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7177EB9B-1524-4A5C-8E55-A70F0EF198EB-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2092\" data-permalink=\"https:\/\/paperjewelz.com\/86894e2a-13fe-4d4d-aa75-9dd936060044\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605933&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0099009900990099&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"86894E2A-13FE-4D4D-AA75-9DD936060044\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2092\" data-permalink=\"https:\/\/paperjewelz.com\/86894e2a-13fe-4d4d-aa75-9dd936060044\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605933&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.0099009900990099&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"86894E2A-13FE-4D4D-AA75-9DD936060044\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 52 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2092\" data-link=\"https:\/\/paperjewelz.com\/86894e2a-13fe-4d4d-aa75-9dd936060044\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/86894E2A-13FE-4D4D-AA75-9DD936060044-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2090\" data-permalink=\"https:\/\/paperjewelz.com\/f9ccc0f3-2cee-48bd-86f7-a9d94a0551a6\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605985&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2090\" data-permalink=\"https:\/\/paperjewelz.com\/f9ccc0f3-2cee-48bd-86f7-a9d94a0551a6\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757605985&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 53 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2090\" data-link=\"https:\/\/paperjewelz.com\/f9ccc0f3-2cee-48bd-86f7-a9d94a0551a6\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/F9CCC0F3-2CEE-48BD-86F7-A9D94A0551A6-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2085\" data-permalink=\"https:\/\/paperjewelz.com\/a631c0c2-8acb-4bb4-844f-683def75bb42\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608151&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"A631C0C2-8ACB-4BB4-844F-683DEF75BB42\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2085\" data-permalink=\"https:\/\/paperjewelz.com\/a631c0c2-8acb-4bb4-844f-683def75bb42\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608151&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"A631C0C2-8ACB-4BB4-844F-683DEF75BB42\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 54 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2085\" data-link=\"https:\/\/paperjewelz.com\/a631c0c2-8acb-4bb4-844f-683def75bb42\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A631C0C2-8ACB-4BB4-844F-683DEF75BB42-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2086\" data-permalink=\"https:\/\/paperjewelz.com\/c17fda71-61e3-4ae0-bab3-167cbd368400\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608102&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"C17FDA71-61E3-4AE0-BAB3-167CBD368400\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2086\" data-permalink=\"https:\/\/paperjewelz.com\/c17fda71-61e3-4ae0-bab3-167cbd368400\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608102&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"C17FDA71-61E3-4AE0-BAB3-167CBD368400\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 55 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2086\" data-link=\"https:\/\/paperjewelz.com\/c17fda71-61e3-4ae0-bab3-167cbd368400\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C17FDA71-61E3-4AE0-BAB3-167CBD368400-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2087\" data-permalink=\"https:\/\/paperjewelz.com\/7c80453a-ee5c-489c-b4ca-aa119c3b5b2a\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608059&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7C80453A-EE5C-489C-B4CA-AA119C3B5B2A\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2087\" data-permalink=\"https:\/\/paperjewelz.com\/7c80453a-ee5c-489c-b4ca-aa119c3b5b2a\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608059&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7C80453A-EE5C-489C-B4CA-AA119C3B5B2A\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 56 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2087\" data-link=\"https:\/\/paperjewelz.com\/7c80453a-ee5c-489c-b4ca-aa119c3b5b2a\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7C80453A-EE5C-489C-B4CA-AA119C3B5B2A-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2088\" data-permalink=\"https:\/\/paperjewelz.com\/3c56c830-09fb-4fea-b587-56739091cf70\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608023&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"3C56C830-09FB-4FEA-B587-56739091CF70\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2088\" data-permalink=\"https:\/\/paperjewelz.com\/3c56c830-09fb-4fea-b587-56739091cf70\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608023&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"3C56C830-09FB-4FEA-B587-56739091CF70\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 57 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2088\" data-link=\"https:\/\/paperjewelz.com\/3c56c830-09fb-4fea-b587-56739091cf70\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/3C56C830-09FB-4FEA-B587-56739091CF70-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2089\" data-permalink=\"https:\/\/paperjewelz.com\/c3227c6c-38c1-4a29-a33b-4d0bda5c7d7d\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757606086&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2089\" data-permalink=\"https:\/\/paperjewelz.com\/c3227c6c-38c1-4a29-a33b-4d0bda5c7d7d\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757606086&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 58 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2089\" data-link=\"https:\/\/paperjewelz.com\/c3227c6c-38c1-4a29-a33b-4d0bda5c7d7d\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C3227C6C-38C1-4A29-A33B-4D0BDA5C7D7D-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2084\" data-permalink=\"https:\/\/paperjewelz.com\/672132ea-defa-4d48-a09a-fc0dba5b1355\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608169&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"672132EA-DEFA-4D48-A09A-FC0DBA5B1355\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2084\" data-permalink=\"https:\/\/paperjewelz.com\/672132ea-defa-4d48-a09a-fc0dba5b1355\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757608169&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"672132EA-DEFA-4D48-A09A-FC0DBA5B1355\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 59 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2084\" data-link=\"https:\/\/paperjewelz.com\/672132ea-defa-4d48-a09a-fc0dba5b1355\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/672132EA-DEFA-4D48-A09A-FC0DBA5B1355-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2059\" data-permalink=\"https:\/\/paperjewelz.com\/19d3935f-9313-4ba1-9e29-b0d1de1f4fa6\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337120&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2059\" data-permalink=\"https:\/\/paperjewelz.com\/19d3935f-9313-4ba1-9e29-b0d1de1f4fa6\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337120&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 60 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2059\" data-link=\"https:\/\/paperjewelz.com\/19d3935f-9313-4ba1-9e29-b0d1de1f4fa6\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/19D3935F-9313-4BA1-9E29-B0D1DE1F4FA6-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2050\" data-permalink=\"https:\/\/paperjewelz.com\/5f0fc16c-b796-4368-833b-aa2a27d700f1\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339861&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"5F0FC16C-B796-4368-833B-AA2A27D700F1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2050\" data-permalink=\"https:\/\/paperjewelz.com\/5f0fc16c-b796-4368-833b-aa2a27d700f1\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339861&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"5F0FC16C-B796-4368-833B-AA2A27D700F1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 61 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2050\" data-link=\"https:\/\/paperjewelz.com\/?attachment_id=2050\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/5F0FC16C-B796-4368-833B-AA2A27D700F1-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2046\" data-permalink=\"https:\/\/paperjewelz.com\/1771709b-afb2-4845-b2a4-42596885931f\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1771709B-AFB2-4845-B2A4-42596885931F-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757336798&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1771709B-AFB2-4845-B2A4-42596885931F\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1771709B-AFB2-4845-B2A4-42596885931F-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2046\" data-permalink=\"https:\/\/paperjewelz.com\/1771709b-afb2-4845-b2a4-42596885931f\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1771709B-AFB2-4845-B2A4-42596885931F-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757336798&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1771709B-AFB2-4845-B2A4-42596885931F\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1771709B-AFB2-4845-B2A4-42596885931F-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2046\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1771709B-AFB2-4845-B2A4-42596885931F-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1771709B-AFB2-4845-B2A4-42596885931F.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2041\" data-permalink=\"https:\/\/paperjewelz.com\/7b1a4bc9-d1ff-4275-b22a-61d7814dc980\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337279&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7B1A4BC9-D1FF-4275-B22A-61D7814DC980\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2041\" data-permalink=\"https:\/\/paperjewelz.com\/7b1a4bc9-d1ff-4275-b22a-61d7814dc980\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337279&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7B1A4BC9-D1FF-4275-B22A-61D7814DC980\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 62 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2041\" data-link=\"https:\/\/paperjewelz.com\/7b1a4bc9-d1ff-4275-b22a-61d7814dc980\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B1A4BC9-D1FF-4275-B22A-61D7814DC980-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2042\" data-permalink=\"https:\/\/paperjewelz.com\/dca28b4e-d9dd-4971-8841-5dff9c1363b2\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337253&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"DCA28B4E-D9DD-4971-8841-5DFF9C1363B2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2042\" data-permalink=\"https:\/\/paperjewelz.com\/dca28b4e-d9dd-4971-8841-5dff9c1363b2\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337253&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"DCA28B4E-D9DD-4971-8841-5DFF9C1363B2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 63 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2042\" data-link=\"https:\/\/paperjewelz.com\/dca28b4e-d9dd-4971-8841-5dff9c1363b2\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/DCA28B4E-D9DD-4971-8841-5DFF9C1363B2-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2043\" data-permalink=\"https:\/\/paperjewelz.com\/9a9a64b1-050f-4c64-a504-2fc509372ce1\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337163&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"9A9A64B1-050F-4C64-A504-2FC509372CE1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2043\" data-permalink=\"https:\/\/paperjewelz.com\/9a9a64b1-050f-4c64-a504-2fc509372ce1\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337163&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"9A9A64B1-050F-4C64-A504-2FC509372CE1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 64 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2043\" data-link=\"https:\/\/paperjewelz.com\/9a9a64b1-050f-4c64-a504-2fc509372ce1\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/9A9A64B1-050F-4C64-A504-2FC509372CE1-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2044\" data-permalink=\"https:\/\/paperjewelz.com\/8e995b25-75c0-46bd-ad64-6a59bf624f37\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337198&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"8E995B25-75C0-46BD-AD64-6A59BF624F37\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2044\" data-permalink=\"https:\/\/paperjewelz.com\/8e995b25-75c0-46bd-ad64-6a59bf624f37\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337198&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"8E995B25-75C0-46BD-AD64-6A59BF624F37\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 65 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2044\" data-link=\"https:\/\/paperjewelz.com\/8e995b25-75c0-46bd-ad64-6a59bf624f37\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/8E995B25-75C0-46BD-AD64-6A59BF624F37-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2045\" data-permalink=\"https:\/\/paperjewelz.com\/7b19b9ab-f17b-41a9-aba5-a5c0e25f9e35\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337068&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2045\" data-permalink=\"https:\/\/paperjewelz.com\/7b19b9ab-f17b-41a9-aba5-a5c0e25f9e35\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337068&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 66 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2045\" data-link=\"https:\/\/paperjewelz.com\/7b19b9ab-f17b-41a9-aba5-a5c0e25f9e35\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7B19B9AB-F17B-41A9-ABA5-A5C0E25F9E35-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2040\" data-permalink=\"https:\/\/paperjewelz.com\/fe7d36b6-c189-4ebe-81dd-0dddd9412998\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337301&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"FE7D36B6-C189-4EBE-81DD-0DDDD9412998\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2040\" data-permalink=\"https:\/\/paperjewelz.com\/fe7d36b6-c189-4ebe-81dd-0dddd9412998\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757337301&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"FE7D36B6-C189-4EBE-81DD-0DDDD9412998\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 67 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2040\" data-link=\"https:\/\/paperjewelz.com\/fe7d36b6-c189-4ebe-81dd-0dddd9412998\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/FE7D36B6-C189-4EBE-81DD-0DDDD9412998-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2039\" data-permalink=\"https:\/\/paperjewelz.com\/1afaa781-1b62-4927-88da-9b6a71fd3e9b\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338718&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1AFAA781-1B62-4927-88DA-9B6A71FD3E9B\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2039\" data-permalink=\"https:\/\/paperjewelz.com\/1afaa781-1b62-4927-88da-9b6a71fd3e9b\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338718&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1AFAA781-1B62-4927-88DA-9B6A71FD3E9B\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 68 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2039\" data-link=\"https:\/\/paperjewelz.com\/1afaa781-1b62-4927-88da-9b6a71fd3e9b\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1AFAA781-1B62-4927-88DA-9B6A71FD3E9B-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2038\" data-permalink=\"https:\/\/paperjewelz.com\/289ec76e-9bec-4806-a389-8687ba58cb3d\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338756&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"289EC76E-9BEC-4806-A389-8687BA58CB3D\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2038\" data-permalink=\"https:\/\/paperjewelz.com\/289ec76e-9bec-4806-a389-8687ba58cb3d\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338756&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"289EC76E-9BEC-4806-A389-8687BA58CB3D\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 69 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2038\" data-link=\"https:\/\/paperjewelz.com\/289ec76e-9bec-4806-a389-8687ba58cb3d\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/289EC76E-9BEC-4806-A389-8687BA58CB3D-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2037\" data-permalink=\"https:\/\/paperjewelz.com\/39c18525-1b93-4f3a-8e0c-b1f014f7e7fe\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/39C18525-1B93-4F3A-8E0C-B1F014F7E7FE-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338829&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"39C18525-1B93-4F3A-8E0C-B1F014F7E7FE\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/39C18525-1B93-4F3A-8E0C-B1F014F7E7FE-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2037\" data-permalink=\"https:\/\/paperjewelz.com\/39c18525-1b93-4f3a-8e0c-b1f014f7e7fe\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/39C18525-1B93-4F3A-8E0C-B1F014F7E7FE-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338829&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"39C18525-1B93-4F3A-8E0C-B1F014F7E7FE\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/39C18525-1B93-4F3A-8E0C-B1F014F7E7FE-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2037\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/39C18525-1B93-4F3A-8E0C-B1F014F7E7FE-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/39C18525-1B93-4F3A-8E0C-B1F014F7E7FE.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2036\" data-permalink=\"https:\/\/paperjewelz.com\/6468b89b-8c48-4d68-a204-56e9525ac030\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338801&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6468B89B-8C48-4D68-A204-56E9525AC030\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2036\" data-permalink=\"https:\/\/paperjewelz.com\/6468b89b-8c48-4d68-a204-56e9525ac030\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338801&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6468B89B-8C48-4D68-A204-56E9525AC030\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 70 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2036\" data-link=\"https:\/\/paperjewelz.com\/6468b89b-8c48-4d68-a204-56e9525ac030\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6468B89B-8C48-4D68-A204-56E9525AC030-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2031\" data-permalink=\"https:\/\/paperjewelz.com\/6d9e38f4-7989-40d0-81aa-045785dddd3e\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6D9E38F4-7989-40D0-81AA-045785DDDD3E-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339025&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6D9E38F4-7989-40D0-81AA-045785DDDD3E\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6D9E38F4-7989-40D0-81AA-045785DDDD3E-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2031\" data-permalink=\"https:\/\/paperjewelz.com\/6d9e38f4-7989-40d0-81aa-045785dddd3e\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6D9E38F4-7989-40D0-81AA-045785DDDD3E-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339025&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"6D9E38F4-7989-40D0-81AA-045785DDDD3E\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6D9E38F4-7989-40D0-81AA-045785DDDD3E-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2031\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6D9E38F4-7989-40D0-81AA-045785DDDD3E-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/6D9E38F4-7989-40D0-81AA-045785DDDD3E.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2032\" data-permalink=\"https:\/\/paperjewelz.com\/12519205-1804-4612-998e-9d0d426cd2a3\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339000&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"12519205-1804-4612-998E-9D0D426CD2A3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2032\" data-permalink=\"https:\/\/paperjewelz.com\/12519205-1804-4612-998e-9d0d426cd2a3\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339000&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"12519205-1804-4612-998E-9D0D426CD2A3\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 71 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2032\" data-link=\"https:\/\/paperjewelz.com\/12519205-1804-4612-998e-9d0d426cd2a3\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/12519205-1804-4612-998E-9D0D426CD2A3-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2033\" data-permalink=\"https:\/\/paperjewelz.com\/11d12636-61f3-4de9-9820-70cd3a492cb5\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338955&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"11D12636-61F3-4DE9-9820-70CD3A492CB5\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2033\" data-permalink=\"https:\/\/paperjewelz.com\/11d12636-61f3-4de9-9820-70cd3a492cb5\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338955&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"11D12636-61F3-4DE9-9820-70CD3A492CB5\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 72 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2033\" data-link=\"https:\/\/paperjewelz.com\/11d12636-61f3-4de9-9820-70cd3a492cb5\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/11D12636-61F3-4DE9-9820-70CD3A492CB5-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2034\" data-permalink=\"https:\/\/paperjewelz.com\/7142c6a1-2bd3-4a16-9107-bb7337c112c1\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7142C6A1-2BD3-4A16-9107-BB7337C112C1-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338926&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7142C6A1-2BD3-4A16-9107-BB7337C112C1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7142C6A1-2BD3-4A16-9107-BB7337C112C1-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2034\" data-permalink=\"https:\/\/paperjewelz.com\/7142c6a1-2bd3-4a16-9107-bb7337c112c1\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7142C6A1-2BD3-4A16-9107-BB7337C112C1-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338926&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"7142C6A1-2BD3-4A16-9107-BB7337C112C1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7142C6A1-2BD3-4A16-9107-BB7337C112C1-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2034\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7142C6A1-2BD3-4A16-9107-BB7337C112C1-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/7142C6A1-2BD3-4A16-9107-BB7337C112C1.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2035\" data-permalink=\"https:\/\/paperjewelz.com\/61a64d66-4dff-4495-8a84-e645869b6937\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/61A64D66-4DFF-4495-8A84-E645869B6937-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338860&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"61A64D66-4DFF-4495-8A84-E645869B6937\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/61A64D66-4DFF-4495-8A84-E645869B6937-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2035\" data-permalink=\"https:\/\/paperjewelz.com\/61a64d66-4dff-4495-8a84-e645869b6937\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/61A64D66-4DFF-4495-8A84-E645869B6937-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757338860&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"61A64D66-4DFF-4495-8A84-E645869B6937\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/61A64D66-4DFF-4495-8A84-E645869B6937-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2035\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/61A64D66-4DFF-4495-8A84-E645869B6937-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/61A64D66-4DFF-4495-8A84-E645869B6937-768x1024.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2030\" data-permalink=\"https:\/\/paperjewelz.com\/690d09f0-f865-46ef-b17c-55aead8daadd\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339584&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"690D09F0-F865-46EF-B17C-55AEAD8DAADD\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2030\" data-permalink=\"https:\/\/paperjewelz.com\/690d09f0-f865-46ef-b17c-55aead8daadd\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339584&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"690D09F0-F865-46EF-B17C-55AEAD8DAADD\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 73 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2030\" data-link=\"https:\/\/paperjewelz.com\/690d09f0-f865-46ef-b17c-55aead8daadd\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/690D09F0-F865-46EF-B17C-55AEAD8DAADD-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2029\" data-permalink=\"https:\/\/paperjewelz.com\/1ef4031d-29c5-47ec-b8ff-1f669f9e6652\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339632&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1EF4031D-29C5-47EC-B8FF-1F669F9E6652\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2029\" data-permalink=\"https:\/\/paperjewelz.com\/1ef4031d-29c5-47ec-b8ff-1f669f9e6652\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339632&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1EF4031D-29C5-47EC-B8FF-1F669F9E6652\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 74 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2029\" data-link=\"https:\/\/paperjewelz.com\/1ef4031d-29c5-47ec-b8ff-1f669f9e6652\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1EF4031D-29C5-47EC-B8FF-1F669F9E6652-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"2028\" data-permalink=\"https:\/\/paperjewelz.com\/499ea960-2c16-4063-bac8-00598f3e6a52\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339749&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"499EA960-2C16-4063-BAC8-00598F3E6A52\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2028\" data-permalink=\"https:\/\/paperjewelz.com\/499ea960-2c16-4063-bac8-00598f3e6a52\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339749&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"499EA960-2C16-4063-BAC8-00598F3E6A52\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-scaled.jpeg?fit=525%2C700&amp;ssl=1\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 75 of 104 in full-screen\"srcset=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-768x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-768x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-768x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-768x1024.jpeg?strip=info&#038;w=1920&#038;ssl=1 1920w\" alt=\"\" data-height=\"2560\" data-id=\"2028\" data-link=\"https:\/\/paperjewelz.com\/499ea960-2c16-4063-bac8-00598f3e6a52\/\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-768x1024.jpeg\" data-width=\"1920\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/499EA960-2C16-4063-BAC8-00598F3E6A52-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2027\" data-permalink=\"https:\/\/paperjewelz.com\/aca865d6-4dd6-4ed4-b3e2-ddb7ef87d377\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/ACA865D6-4DD6-4ED4-B3E2-DDB7EF87D377-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339790&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ACA865D6-4DD6-4ED4-B3E2-DDB7EF87D377\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/ACA865D6-4DD6-4ED4-B3E2-DDB7EF87D377-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2027\" data-permalink=\"https:\/\/paperjewelz.com\/aca865d6-4dd6-4ed4-b3e2-ddb7ef87d377\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/ACA865D6-4DD6-4ED4-B3E2-DDB7EF87D377-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339790&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"ACA865D6-4DD6-4ED4-B3E2-DDB7EF87D377\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/ACA865D6-4DD6-4ED4-B3E2-DDB7EF87D377-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2027\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/ACA865D6-4DD6-4ED4-B3E2-DDB7EF87D377-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/ACA865D6-4DD6-4ED4-B3E2-DDB7EF87D377.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2026\" data-permalink=\"https:\/\/paperjewelz.com\/0fe53117-c171-4d12-98c5-13c2016e363e\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0FE53117-C171-4D12-98C5-13C2016E363E-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339814&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"0FE53117-C171-4D12-98C5-13C2016E363E\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0FE53117-C171-4D12-98C5-13C2016E363E-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2026\" data-permalink=\"https:\/\/paperjewelz.com\/0fe53117-c171-4d12-98c5-13c2016e363e\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0FE53117-C171-4D12-98C5-13C2016E363E-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339814&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"0FE53117-C171-4D12-98C5-13C2016E363E\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0FE53117-C171-4D12-98C5-13C2016E363E-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2026\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0FE53117-C171-4D12-98C5-13C2016E363E-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0FE53117-C171-4D12-98C5-13C2016E363E.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2021\" data-permalink=\"https:\/\/paperjewelz.com\/aa95ece0-4100-4e1d-ba95-b0e3b5b9655f\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/AA95ECE0-4100-4E1D-BA95-B0E3B5B9655F-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757340008&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"AA95ECE0-4100-4E1D-BA95-B0E3B5B9655F\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/AA95ECE0-4100-4E1D-BA95-B0E3B5B9655F-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2021\" data-permalink=\"https:\/\/paperjewelz.com\/aa95ece0-4100-4e1d-ba95-b0e3b5b9655f\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/AA95ECE0-4100-4E1D-BA95-B0E3B5B9655F-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757340008&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"AA95ECE0-4100-4E1D-BA95-B0E3B5B9655F\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/AA95ECE0-4100-4E1D-BA95-B0E3B5B9655F-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2021\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/AA95ECE0-4100-4E1D-BA95-B0E3B5B9655F-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/AA95ECE0-4100-4E1D-BA95-B0E3B5B9655F.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2022\" data-permalink=\"https:\/\/paperjewelz.com\/a48c3645-e87a-47a6-8f0f-fb45768b0ed6\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A48C3645-E87A-47A6-8F0F-FB45768B0ED6-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339967&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"A48C3645-E87A-47A6-8F0F-FB45768B0ED6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A48C3645-E87A-47A6-8F0F-FB45768B0ED6-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2022\" data-permalink=\"https:\/\/paperjewelz.com\/a48c3645-e87a-47a6-8f0f-fb45768b0ed6\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A48C3645-E87A-47A6-8F0F-FB45768B0ED6-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339967&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"A48C3645-E87A-47A6-8F0F-FB45768B0ED6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A48C3645-E87A-47A6-8F0F-FB45768B0ED6-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2022\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A48C3645-E87A-47A6-8F0F-FB45768B0ED6-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/A48C3645-E87A-47A6-8F0F-FB45768B0ED6.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2023\" data-permalink=\"https:\/\/paperjewelz.com\/ec7baa2a-a0f3-4def-98a4-63603c5d9506\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC7BAA2A-A0F3-4DEF-98A4-63603C5D9506-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339940&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"EC7BAA2A-A0F3-4DEF-98A4-63603C5D9506\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC7BAA2A-A0F3-4DEF-98A4-63603C5D9506-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2023\" data-permalink=\"https:\/\/paperjewelz.com\/ec7baa2a-a0f3-4def-98a4-63603c5d9506\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC7BAA2A-A0F3-4DEF-98A4-63603C5D9506-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339940&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"EC7BAA2A-A0F3-4DEF-98A4-63603C5D9506\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC7BAA2A-A0F3-4DEF-98A4-63603C5D9506-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2023\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC7BAA2A-A0F3-4DEF-98A4-63603C5D9506-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC7BAA2A-A0F3-4DEF-98A4-63603C5D9506.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2024\" data-permalink=\"https:\/\/paperjewelz.com\/0f403d10-7516-4ba3-84fd-69b12ada132a\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0F403D10-7516-4BA3-84FD-69B12ADA132A-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339901&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"0F403D10-7516-4BA3-84FD-69B12ADA132A\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0F403D10-7516-4BA3-84FD-69B12ADA132A-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2024\" data-permalink=\"https:\/\/paperjewelz.com\/0f403d10-7516-4ba3-84fd-69b12ada132a\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0F403D10-7516-4BA3-84FD-69B12ADA132A-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339901&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"0F403D10-7516-4BA3-84FD-69B12ADA132A\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0F403D10-7516-4BA3-84FD-69B12ADA132A-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2024\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0F403D10-7516-4BA3-84FD-69B12ADA132A-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/0F403D10-7516-4BA3-84FD-69B12ADA132A.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2025\" data-permalink=\"https:\/\/paperjewelz.com\/1fc01e8c-140e-4f74-be75-7d2406384bf2\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1FC01E8C-140E-4F74-BE75-7D2406384BF2-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339836&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1FC01E8C-140E-4F74-BE75-7D2406384BF2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1FC01E8C-140E-4F74-BE75-7D2406384BF2-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2025\" data-permalink=\"https:\/\/paperjewelz.com\/1fc01e8c-140e-4f74-be75-7d2406384bf2\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1FC01E8C-140E-4F74-BE75-7D2406384BF2-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757339836&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"1FC01E8C-140E-4F74-BE75-7D2406384BF2\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1FC01E8C-140E-4F74-BE75-7D2406384BF2-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2025\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1FC01E8C-140E-4F74-BE75-7D2406384BF2-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/1FC01E8C-140E-4F74-BE75-7D2406384BF2.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2020\" data-permalink=\"https:\/\/paperjewelz.com\/c5ff6bef-c47b-4672-8881-fca9add4154c\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C5FF6BEF-C47B-4672-8881-FCA9ADD4154C-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757340047&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"C5FF6BEF-C47B-4672-8881-FCA9ADD4154C\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C5FF6BEF-C47B-4672-8881-FCA9ADD4154C-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2020\" data-permalink=\"https:\/\/paperjewelz.com\/c5ff6bef-c47b-4672-8881-fca9add4154c\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C5FF6BEF-C47B-4672-8881-FCA9ADD4154C-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757340047&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;32&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"C5FF6BEF-C47B-4672-8881-FCA9ADD4154C\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C5FF6BEF-C47B-4672-8881-FCA9ADD4154C-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2020\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C5FF6BEF-C47B-4672-8881-FCA9ADD4154C-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/C5FF6BEF-C47B-4672-8881-FCA9ADD4154C.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"2019\" data-permalink=\"https:\/\/paperjewelz.com\/ec876cb7-e4ad-4563-bbf9-e4ea2e97c135\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC876CB7-E4AD-4563-BBF9-E4EA2E97C135-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757340088&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"EC876CB7-E4AD-4563-BBF9-E4EA2E97C135\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC876CB7-E4AD-4563-BBF9-E4EA2E97C135-scaled.jpeg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"2019\" data-permalink=\"https:\/\/paperjewelz.com\/ec876cb7-e4ad-4563-bbf9-e4ea2e97c135\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC876CB7-E4AD-4563-BBF9-E4EA2E97C135-scaled.jpeg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1757340088&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.01&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"EC876CB7-E4AD-4563-BBF9-E4EA2E97C135\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC876CB7-E4AD-4563-BBF9-E4EA2E97C135-scaled.jpeg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"2019\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC876CB7-E4AD-4563-BBF9-E4EA2E97C135-768x1024.jpeg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/09\/EC876CB7-E4AD-4563-BBF9-E4EA2E97C135-768x1024.jpeg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"720\" width=\"525\" decoding=\"async\" data-attachment-id=\"1773\" data-permalink=\"https:\/\/paperjewelz.com\/img_2395\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2395.jpg?fit=1853%2C2541&amp;ssl=1\" data-orig-size=\"1853,2541\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036628&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2395\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2395.jpg?fit=525%2C720&amp;ssl=1\" data-attachment-id=\"1773\" data-permalink=\"https:\/\/paperjewelz.com\/img_2395\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2395.jpg?fit=1853%2C2541&amp;ssl=1\" data-orig-size=\"1853,2541\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036628&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2395\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2395.jpg?fit=525%2C720&amp;ssl=1\" alt=\"\" data-id=\"1773\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2395-747x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2395.jpg?resize=525%2C720&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"763\" width=\"525\" decoding=\"async\" data-attachment-id=\"1772\" data-permalink=\"https:\/\/paperjewelz.com\/img_2394\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2394-scaled.jpg?fit=1762%2C2560&amp;ssl=1\" data-orig-size=\"1762,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036608&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2394\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2394-scaled.jpg?fit=525%2C763&amp;ssl=1\" data-attachment-id=\"1772\" data-permalink=\"https:\/\/paperjewelz.com\/img_2394\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2394-scaled.jpg?fit=1762%2C2560&amp;ssl=1\" data-orig-size=\"1762,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036608&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2394\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2394-scaled.jpg?fit=525%2C763&amp;ssl=1\" alt=\"\" data-id=\"1772\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2394-705x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2394.jpg?resize=525%2C763&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"766\" width=\"525\" decoding=\"async\" data-attachment-id=\"1771\" data-permalink=\"https:\/\/paperjewelz.com\/img_2393\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2393-scaled.jpg?fit=1755%2C2560&amp;ssl=1\" data-orig-size=\"1755,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036604&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2393\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2393-scaled.jpg?fit=525%2C766&amp;ssl=1\" data-attachment-id=\"1771\" data-permalink=\"https:\/\/paperjewelz.com\/img_2393\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2393-scaled.jpg?fit=1755%2C2560&amp;ssl=1\" data-orig-size=\"1755,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036604&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;64&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2393\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2393-scaled.jpg?fit=525%2C766&amp;ssl=1\" alt=\"\" data-id=\"1771\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2393-702x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2393.jpg?resize=525%2C766&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"682\" width=\"525\" decoding=\"async\" data-attachment-id=\"1770\" data-permalink=\"https:\/\/paperjewelz.com\/img_2392\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2392-scaled.jpg?fit=1971%2C2560&amp;ssl=1\" data-orig-size=\"1971,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036601&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2392\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2392-scaled.jpg?fit=525%2C682&amp;ssl=1\" data-attachment-id=\"1770\" data-permalink=\"https:\/\/paperjewelz.com\/img_2392\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2392-scaled.jpg?fit=1971%2C2560&amp;ssl=1\" data-orig-size=\"1971,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036601&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2392\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2392-scaled.jpg?fit=525%2C682&amp;ssl=1\" alt=\"\" data-id=\"1770\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2392-788x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2392.jpg?resize=525%2C682&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"695\" width=\"525\" decoding=\"async\" data-attachment-id=\"1769\" data-permalink=\"https:\/\/paperjewelz.com\/img_2391\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2391-scaled.jpg?fit=1933%2C2560&amp;ssl=1\" data-orig-size=\"1933,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036597&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2391\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2391-scaled.jpg?fit=525%2C695&amp;ssl=1\" data-attachment-id=\"1769\" data-permalink=\"https:\/\/paperjewelz.com\/img_2391\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2391-scaled.jpg?fit=1933%2C2560&amp;ssl=1\" data-orig-size=\"1933,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036597&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2391\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2391-scaled.jpg?fit=525%2C695&amp;ssl=1\" alt=\"\" data-id=\"1769\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2391-773x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2391.jpg?resize=525%2C695&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"774\" width=\"525\" decoding=\"async\" data-attachment-id=\"1774\" data-permalink=\"https:\/\/paperjewelz.com\/img_2396\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2396.jpg?fit=1717%2C2530&amp;ssl=1\" data-orig-size=\"1717,2530\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036657&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2396\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2396.jpg?fit=525%2C774&amp;ssl=1\" data-attachment-id=\"1774\" data-permalink=\"https:\/\/paperjewelz.com\/img_2396\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2396.jpg?fit=1717%2C2530&amp;ssl=1\" data-orig-size=\"1717,2530\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036657&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2396\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2396.jpg?fit=525%2C774&amp;ssl=1\" alt=\"\" data-id=\"1774\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2396-695x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2396.jpg?resize=525%2C774&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"588\" width=\"525\" decoding=\"async\" data-attachment-id=\"1764\" data-permalink=\"https:\/\/paperjewelz.com\/img_2385\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2385.jpg?fit=2046%2C2290&amp;ssl=1\" data-orig-size=\"2046,2290\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036207&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2385\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2385.jpg?fit=525%2C588&amp;ssl=1\" data-attachment-id=\"1764\" data-permalink=\"https:\/\/paperjewelz.com\/img_2385\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2385.jpg?fit=2046%2C2290&amp;ssl=1\" data-orig-size=\"2046,2290\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036207&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2385\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2385.jpg?fit=525%2C588&amp;ssl=1\" alt=\"\" data-id=\"1764\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2385-915x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2385.jpg?resize=525%2C588&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"603\" width=\"525\" decoding=\"async\" data-attachment-id=\"1765\" data-permalink=\"https:\/\/paperjewelz.com\/img_2386\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2386.jpg?fit=1971%2C2263&amp;ssl=1\" data-orig-size=\"1971,2263\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036215&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2386\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2386.jpg?fit=525%2C603&amp;ssl=1\" data-attachment-id=\"1765\" data-permalink=\"https:\/\/paperjewelz.com\/img_2386\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2386.jpg?fit=1971%2C2263&amp;ssl=1\" data-orig-size=\"1971,2263\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036215&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;40&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2386\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2386.jpg?fit=525%2C603&amp;ssl=1\" alt=\"\" data-id=\"1765\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2386-892x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2386.jpg?resize=525%2C603&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:66.74757%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"515\" width=\"525\" decoding=\"async\" data-attachment-id=\"1766\" data-permalink=\"https:\/\/paperjewelz.com\/img_2387\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2387.jpg?fit=1957%2C1919&amp;ssl=1\" data-orig-size=\"1957,1919\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036238&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2387\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2387.jpg?fit=525%2C515&amp;ssl=1\" data-attachment-id=\"1766\" data-permalink=\"https:\/\/paperjewelz.com\/img_2387\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2387.jpg?fit=1957%2C1919&amp;ssl=1\" data-orig-size=\"1957,1919\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036238&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2387\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2387.jpg?fit=525%2C515&amp;ssl=1\" alt=\"\" data-id=\"1766\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2387-1024x1004.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2387.jpg?resize=525%2C515&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"526\" width=\"525\" decoding=\"async\" data-attachment-id=\"1767\" data-permalink=\"https:\/\/paperjewelz.com\/img_2388\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2388.jpg?fit=2324%2C2329&amp;ssl=1\" data-orig-size=\"2324,2329\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036244&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2388\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2388.jpg?fit=525%2C526&amp;ssl=1\" data-attachment-id=\"1767\" data-permalink=\"https:\/\/paperjewelz.com\/img_2388\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2388.jpg?fit=2324%2C2329&amp;ssl=1\" data-orig-size=\"2324,2329\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036244&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2388\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2388.jpg?fit=525%2C526&amp;ssl=1\" alt=\"\" data-id=\"1767\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2388-1022x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2388.jpg?resize=525%2C526&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.25243%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"718\" width=\"525\" decoding=\"async\" data-attachment-id=\"1768\" data-permalink=\"https:\/\/paperjewelz.com\/img_2390\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2390-scaled.jpg?fit=1871%2C2560&amp;ssl=1\" data-orig-size=\"1871,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036594&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2390\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2390-scaled.jpg?fit=525%2C718&amp;ssl=1\" data-attachment-id=\"1768\" data-permalink=\"https:\/\/paperjewelz.com\/img_2390\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2390-scaled.jpg?fit=1871%2C2560&amp;ssl=1\" data-orig-size=\"1871,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPad Air 2&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1744036594&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.3&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.03030303030303&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2390\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2390-scaled.jpg?fit=525%2C718&amp;ssl=1\" alt=\"\" data-id=\"1768\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2390-749x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/04\/IMG_2390.jpg?resize=525%2C718&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"1619\" data-permalink=\"https:\/\/paperjewelz.com\/img_20250320_201356364_hdr\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201356364_HDR-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1742501637&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.23&quot;,&quot;iso&quot;:&quot;1431&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_20250320_201356364_HDR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201356364_HDR-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"1619\" data-permalink=\"https:\/\/paperjewelz.com\/img_20250320_201356364_hdr\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201356364_HDR-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1742501637&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.23&quot;,&quot;iso&quot;:&quot;1431&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_20250320_201356364_HDR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201356364_HDR-scaled.jpg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"1619\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201356364_HDR-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201356364_HDR.jpg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"1618\" data-permalink=\"https:\/\/paperjewelz.com\/img_20250320_201316684_hdr\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201316684_HDR-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1742501597&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.23&quot;,&quot;iso&quot;:&quot;1734&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_20250320_201316684_HDR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201316684_HDR-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"1618\" data-permalink=\"https:\/\/paperjewelz.com\/img_20250320_201316684_hdr\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201316684_HDR-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1742501597&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.23&quot;,&quot;iso&quot;:&quot;1734&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_20250320_201316684_HDR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201316684_HDR-scaled.jpg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"1618\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201316684_HDR-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201316684_HDR.jpg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:33.33333%\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"1616\" data-permalink=\"https:\/\/paperjewelz.com\/img_20250320_201208860\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201208860-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1742501529&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.23&quot;,&quot;iso&quot;:&quot;1063&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_20250320_201208860\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201208860-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"1616\" data-permalink=\"https:\/\/paperjewelz.com\/img_20250320_201208860\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201208860-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1742501529&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.23&quot;,&quot;iso&quot;:&quot;1063&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_20250320_201208860\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201208860-scaled.jpg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"1616\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201208860-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201208860.jpg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\"><figure class=\"tiled-gallery__item\"><img data-recalc-dims=\"1\" height=\"700\" width=\"525\" decoding=\"async\" data-attachment-id=\"1613\" data-permalink=\"https:\/\/paperjewelz.com\/img_20250320_201042451_hdr\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201042451_HDR-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1742501443&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.23&quot;,&quot;iso&quot;:&quot;1519&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_20250320_201042451_HDR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201042451_HDR-scaled.jpg?fit=525%2C700&amp;ssl=1\" data-attachment-id=\"1613\" data-permalink=\"https:\/\/paperjewelz.com\/img_20250320_201042451_hdr\/\" data-orig-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201042451_HDR-scaled.jpg?fit=1920%2C2560&amp;ssl=1\" data-orig-size=\"1920,2560\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.9&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;motorola edge 50 pro&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1742501443&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.23&quot;,&quot;iso&quot;:&quot;1519&quot;,&quot;shutter_speed&quot;:&quot;0.03&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"IMG_20250320_201042451_HDR\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201042451_HDR-scaled.jpg?fit=525%2C700&amp;ssl=1\" alt=\"\" data-id=\"1613\" data-url=\"https:\/\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201042451_HDR-768x1024.jpg\" src=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/03\/IMG_20250320_201042451_HDR.jpg?resize=525%2C700&#038;ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-2191","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>New Collection -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"New Collection -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/paperjewelz.com\/index.php\/new-collection\/\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/paperjewelzvrinda\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-24T05:25:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?ssl=1\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/index.php\\\/new-collection\\\/\",\"url\":\"https:\\\/\\\/paperjewelz.com\\\/index.php\\\/new-collection\\\/\",\"name\":\"New Collection -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/index.php\\\/new-collection\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/index.php\\\/new-collection\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/paperjewelz.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_2714-1024x768.jpg?ssl=1\",\"datePublished\":\"2025-11-24T05:25:42+00:00\",\"dateModified\":\"2025-11-24T05:25:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/index.php\\\/new-collection\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/paperjewelz.com\\\/index.php\\\/new-collection\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/index.php\\\/new-collection\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/paperjewelz.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_2714-1024x768.jpg?ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/paperjewelz.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/IMG_2714-1024x768.jpg?ssl=1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/index.php\\\/new-collection\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/paperjewelz.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"New Collection\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/#website\",\"url\":\"https:\\\/\\\/paperjewelz.com\\\/\",\"name\":\"\",\"description\":\"Where Art Meets Fashion: Elevate Your Style Sustainably\",\"publisher\":{\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/#\\\/schema\\\/person\\\/4505178fb68034a0a153b93aabdbf945\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/paperjewelz.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/paperjewelz.com\\\/#\\\/schema\\\/person\\\/4505178fb68034a0a153b93aabdbf945\",\"name\":\"paperjewelz.ce2599c75f\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/paperjewelz.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Screenshot_22-2-2026_103426_.jpeg?fit=776%2C250&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/paperjewelz.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Screenshot_22-2-2026_103426_.jpeg?fit=776%2C250&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/paperjewelz.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Screenshot_22-2-2026_103426_.jpeg?fit=776%2C250&ssl=1\",\"width\":776,\"height\":250,\"caption\":\"paperjewelz.ce2599c75f\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/paperjewelz.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/cropped-Screenshot_22-2-2026_103426_.jpeg?fit=776%2C250&ssl=1\"},\"sameAs\":[\"http:\\\/\\\/paperjewelz.com\",\"https:\\\/\\\/www.facebook.com\\\/paperjewelzvrinda\",\"https:\\\/\\\/www.instagram.com\\\/paperjewelz_vrinda\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"New Collection -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/paperjewelz.com\/index.php\/new-collection\/","og_locale":"en_US","og_type":"article","og_title":"New Collection -","og_url":"https:\/\/paperjewelz.com\/index.php\/new-collection\/","article_publisher":"https:\/\/www.facebook.com\/paperjewelzvrinda","article_modified_time":"2025-11-24T05:25:46+00:00","og_image":[{"url":"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?ssl=1","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"21 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/paperjewelz.com\/index.php\/new-collection\/","url":"https:\/\/paperjewelz.com\/index.php\/new-collection\/","name":"New Collection -","isPartOf":{"@id":"https:\/\/paperjewelz.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/paperjewelz.com\/index.php\/new-collection\/#primaryimage"},"image":{"@id":"https:\/\/paperjewelz.com\/index.php\/new-collection\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?ssl=1","datePublished":"2025-11-24T05:25:42+00:00","dateModified":"2025-11-24T05:25:46+00:00","breadcrumb":{"@id":"https:\/\/paperjewelz.com\/index.php\/new-collection\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/paperjewelz.com\/index.php\/new-collection\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/paperjewelz.com\/index.php\/new-collection\/#primaryimage","url":"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?ssl=1","contentUrl":"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2025\/11\/IMG_2714-1024x768.jpg?ssl=1"},{"@type":"BreadcrumbList","@id":"https:\/\/paperjewelz.com\/index.php\/new-collection\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/paperjewelz.com\/"},{"@type":"ListItem","position":2,"name":"New Collection"}]},{"@type":"WebSite","@id":"https:\/\/paperjewelz.com\/#website","url":"https:\/\/paperjewelz.com\/","name":"","description":"Where Art Meets Fashion: Elevate Your Style Sustainably","publisher":{"@id":"https:\/\/paperjewelz.com\/#\/schema\/person\/4505178fb68034a0a153b93aabdbf945"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/paperjewelz.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/paperjewelz.com\/#\/schema\/person\/4505178fb68034a0a153b93aabdbf945","name":"paperjewelz.ce2599c75f","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2026\/03\/cropped-Screenshot_22-2-2026_103426_.jpeg?fit=776%2C250&ssl=1","url":"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2026\/03\/cropped-Screenshot_22-2-2026_103426_.jpeg?fit=776%2C250&ssl=1","contentUrl":"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2026\/03\/cropped-Screenshot_22-2-2026_103426_.jpeg?fit=776%2C250&ssl=1","width":776,"height":250,"caption":"paperjewelz.ce2599c75f"},"logo":{"@id":"https:\/\/i0.wp.com\/paperjewelz.com\/wp-content\/uploads\/2026\/03\/cropped-Screenshot_22-2-2026_103426_.jpeg?fit=776%2C250&ssl=1"},"sameAs":["http:\/\/paperjewelz.com","https:\/\/www.facebook.com\/paperjewelzvrinda","https:\/\/www.instagram.com\/paperjewelz_vrinda\/"]}]}},"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PeUeW7-zl","jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/paperjewelz.com\/index.php\/wp-json\/wp\/v2\/pages\/2191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/paperjewelz.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/paperjewelz.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/paperjewelz.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/paperjewelz.com\/index.php\/wp-json\/wp\/v2\/comments?post=2191"}],"version-history":[{"count":1,"href":"https:\/\/paperjewelz.com\/index.php\/wp-json\/wp\/v2\/pages\/2191\/revisions"}],"predecessor-version":[{"id":2232,"href":"https:\/\/paperjewelz.com\/index.php\/wp-json\/wp\/v2\/pages\/2191\/revisions\/2232"}],"wp:attachment":[{"href":"https:\/\/paperjewelz.com\/index.php\/wp-json\/wp\/v2\/media?parent=2191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}